{"id":156,"count":27,"description":"","link":"https:\/\/genkiyagroup.net\/hachinohe\/tag\/%e4%ba%a4%e9%80%9a%e4%ba%8b%e6%95%85%e3%81%ae%e6%b2%bb%e7%99%82","name":"\u4ea4\u901a\u4e8b\u6545\u306e\u6cbb\u7642","slug":"%e4%ba%a4%e9%80%9a%e4%ba%8b%e6%95%85%e3%81%ae%e6%b2%bb%e7%99%82","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/genkiyagroup.net\/hachinohe\/wp-json\/wp\/v2\/tags\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genkiyagroup.net\/hachinohe\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/genkiyagroup.net\/hachinohe\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/genkiyagroup.net\/hachinohe\/wp-json\/wp\/v2\/posts?tags=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}